{"id":2191,"date":"2014-04-05T10:44:24","date_gmt":"2014-04-05T08:44:24","guid":{"rendered":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete.jpg"},"modified":"2014-04-05T10:44:24","modified_gmt":"2014-04-05T08:44:24","slug":"kirschbluete-2","status":"inherit","type":"attachment","link":"http:\/\/www.blog.bettinastadler.de\/wordpress\/2014\/03\/zartes-grun\/kirschbluete-2\/","title":{"rendered":"Kirschbl\u00fcte"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2191","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"240\" src=\"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete-300x240.jpg 300w, http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>bald in voller Bl\u00fcte<\/p>\n"},"caption":{"rendered":"<p>noch zart <a href=\"http:\/\/www.blog.bettinastadler.de\/wordpress\/2014\/03\/zartes-grun\/kirschbluete-2\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"800","height":"640","hwstring_small":"height='96' width='120'","file":"2014\/04\/Kirschbluete.jpg","sizes":{"thumbnail":{"file":"Kirschbluete-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete-150x150.jpg"},"medium":{"file":"Kirschbluete-300x240.jpg","width":"300","height":"240","source_url":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete-300x240.jpg"},"post-thumbnail":{"file":"Kirschbluete-800x198.jpg","width":"800","height":"198","source_url":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete-800x198.jpg"},"full":{"file":"Kirschbluete.jpg","width":800,"height":640,"mime_type":"image\/jpeg","source_url":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":2176,"source_url":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-content\/uploads\/2014\/04\/Kirschbluete.jpg","_links":{"self":[{"href":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-json\/wp\/v2\/media\/2191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blog.bettinastadler.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2191"}]}}